{"id":313,"date":"2015-07-29T13:44:44","date_gmt":"2015-07-29T13:44:44","guid":{"rendered":"https:\/\/zakra-simple-blog.sites.qsandbox.com\/?page_id=4"},"modified":"2021-02-24T07:14:49","modified_gmt":"2021-02-24T07:14:49","slug":"home","status":"publish","type":"page","link":"https:\/\/zakrademos.com\/travel-blog\/","title":{"rendered":"Home"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:90px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-cover aligncenter has-background-dim-40 has-background-dim has-parallax\" style=\"background-image:url(https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/travel.jpg)\"><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div style=\"height:170px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"alignfull has-text-align-center wp-block-heading\" style=\"font-size:75px\"><strong>Discover New Worlds <\/strong><br><strong>with me<\/strong>.<\/h1>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Stou doloremque quo odio repudiandae sunt eveniet,<br>enim voluptate id porro, culpa maiores quis.<\/p>\n\n\n\n<div style=\"height:170px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-black-color has-text-color\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns has-white-background-color has-background is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-black-color has-text-color wp-block-heading\" style=\"font-size:50px\">My story of travelling through the world<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmodtempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam,quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmodtempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam,quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">nderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/about-img.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"700\" src=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/about-img.jpg\" alt=\"\" class=\"wp-image-225\" srcset=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/about-img.jpg 600w, https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/about-img-257x300.jpg 257w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns has-white-background-color has-background is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center has-black-color has-text-color wp-block-heading\" style=\"font-size:50px\"><strong>Recent Blog Post<\/strong><\/h2>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-09.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"450\" src=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-09.jpg\" alt=\"\" class=\"wp-image-354\" srcset=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-09.jpg 900w, https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-09-300x150.jpg 300w, https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-09-768x384.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"has-black-color has-text-color wp-block-heading\" style=\"font-size:32px\">14 Great Travel Backpacks <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmodtempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam,quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zakrademos.com\/travel-blog\/2021\/02\/04\/14-great-travel-backpacks-for-your-next-trip\/\">Read More<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-03.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"450\" src=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-03.jpg\" alt=\"\" class=\"wp-image-196\" srcset=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-03.jpg 900w, https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-03-300x150.jpg 300w, https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-03-768x384.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"has-black-color has-text-color wp-block-heading\" style=\"font-size:32px\">8 Best Things to Do in Thailand<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmodtempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam,quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zakrademos.com\/travel-blog\/2021\/02\/04\/8-best-things-to-do-in-thailand\/\">Read More<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-02.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"450\" src=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-02.jpg\" alt=\"\" class=\"wp-image-195\" srcset=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-02.jpg 900w, https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-02-300x150.jpg 300w, https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/blog-img-02-768x384.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"has-black-color has-text-color wp-block-heading\" style=\"font-size:32px\">The Best Place To Travel in 2021<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmodtempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam,quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zakrademos.com\/travel-blog\/2021\/02\/04\/the-best-place-to-travel-in-2021\/\">Read More<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover aligncenter has-background-dim-10 has-background-dim has-parallax\" style=\"background-image:url(https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/inner-bg.jpg);min-height:600px;aspect-ratio:unset;\"><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h1 class=\"has-text-align-center wp-block-heading\" style=\"font-size:60px\"><strong>Explore A new <\/strong><br><strong>Place With Me.<\/strong><\/h1>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Stou doloremque quo odio repudiandae sunt eveniet,<br>enim voluptate id porro, culpa maiores quis.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-black-color has-text-color\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns has-white-background-color has-background is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center has-black-color has-text-color wp-block-heading\" style=\"font-size:50px\"><strong>What Reader Say<\/strong><\/h2>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image is-style-rounded\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/client-img1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/client-img1.jpg\" alt=\"\" class=\"wp-image-349\"\/><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><strong>Amelia<\/strong> <strong>Margaret<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmodtempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam,quis nostrud exercitation ullamco<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image is-style-rounded\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/client02.jpg\" alt=\"\" class=\"wp-image-188\"\/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><strong>Noah James<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmodtempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam,quis nostrud exercitation ullamco <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image is-style-rounded\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zakrademos.com\/travel-blog\/wp-content\/uploads\/sites\/90\/2021\/02\/client03.jpg\" alt=\"\" class=\"wp-image-190\"\/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><strong>Oliver<\/strong> <strong>Jake<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmodtempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam,quis nostrud exercitation ullamco <\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>My story of travelling through the world Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmodtempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam,quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo consequat. Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"page-templates\/pagebuilder.php","meta":{"zakra_page_container_layout":"centered","zakra_page_sidebar_layout":"no_sidebar","zakra_remove_content_margin":true,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"footnotes":""},"class_list":["post-313","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/zakrademos.com\/travel-blog\/wp-json\/wp\/v2\/pages\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zakrademos.com\/travel-blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zakrademos.com\/travel-blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zakrademos.com\/travel-blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zakrademos.com\/travel-blog\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":0,"href":"https:\/\/zakrademos.com\/travel-blog\/wp-json\/wp\/v2\/pages\/313\/revisions"}],"wp:attachment":[{"href":"https:\/\/zakrademos.com\/travel-blog\/wp-json\/wp\/v2\/media?parent=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}